{"id":4039,"date":"2019-09-02T21:57:21","date_gmt":"2019-09-02T18:57:21","guid":{"rendered":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/"},"modified":"2019-09-02T21:57:22","modified_gmt":"2019-09-02T18:57:22","slug":"calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable","status":"publish","type":"post","link":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/","title":{"rendered":"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p class=\"entradilla\">La ministra de Economa y Empresa en funciones, Nadia Calvio, ha asegurado que la economa espaola y su previsin para el prximo ao sera \u00abms positiva\u00bb si el pas contara ya con un Gobierno \u00abcon una perspectiva de estabilidad para los prximos cuatro aos\u00bb, que le permitira abordar los riesgos e incertidumbres a los que se enfrenta.<\/p>\n<p>En el 33 Encuentro de la Economa Digital y las Telecomunicaciones, organizado por Ametic, Calvio ha incidido en que contar con un Ejecutivo estable permitira abordar la reformas necesarias y dara un mensaje \u00abmuy claro\u00bb a todos los inversores internacionales, que muestran sus dudas antes la falta de estabilidad poltica en Espaa en los prximos aos. <\/p>\n<p> En este sentido, ha defendido que la economa espaola sigue teniendo un comportamiento \u00abmuy positivo\u00bb y ha remarcado que, como reflejan los niveles mnimos de los tipos de inters registrados en la emisin de deuda pblica en Espaa, la percepcin de Espaa entre los inversores internacionales ha mejorado \u00abmucho\u00bb. <\/p>\n<p> \u00abEn mi opinin, claramente nuestra perspectiva sera mas positiva si tuvisemos ya un gobierno\u00bb, ha remarcado Calvio, quien ha incidido en que no se trata solo de que salga adelante la investidura, sino de que haya un Gobierno \u00abque proporcione estabilidad para los prximo cuatro aos\u00bb, algo fundamental para fomentar la inversin y fortalecer el crecimiento econmico y la prosperidad. <\/p>\n<p> En este sentido, ha asegurado que no hay ningn inters en repetir elecciones en el Partido Socialista, porque es el que ha ganado la elecciones y el que la sociedad espaola \u00abclaramente\u00bb quiere que lidere un Gobierno, as como porque \u00ablo ideal\u00bb es que haya cuanto antes un gobierno para afrontar los distintos riesgo e incertidumbres que se esperan para los prximos meses. <\/p>\n<p> \u00abEs indudable que a corto plazo tenemos en el horizonte un conjunto de riesgos y de incertidumbres como la guerra comercial: la posible inestabilidad en alguna economas emergentes como Argentina; la desaceleracin de la economa alemana, que es el motor de crecimiento de la zona euro; o el Brexit, donde si se produce una salida sin acuerdo del Reino Unido de la UE tendr un impacto indudable\u00bb, ha agregado. <\/p>\n<h3 class=\"subhead\">Brexit<\/h3>\n<p>En este sentido, Calvio ha anunciado que varios ministros del Gobierno analizarn esta semana \u00absi es necesario prever mecanismos adicionales\u00bb para afrontar el Brexit, teniendo en cuenta que el desenlace \u00abes difcil de prever\u00bb y que hay que estar preparados \u00abpara lo peor\u00bb.<\/p>\n<p>El presidente del Gobierno en funciones, Pedro Snchez, ha convocado una reunin extraordinaria para esta semana a fin de que los \u00abministros relacionados\u00bb con el Brexit pongan al da la informacin y sus anlisis de cmo est evolucionando la situacin a la luz de los acontecimientos, segn ha afirmado la ministra, en declaraciones a los periodistas.<\/p>\n<\/div>\n<p><script type=\"text\/javascript\">(function(d,s,id){var js,fjs=d.getElementsByTagName(s)[0];if(d.getElementById(id))return;js=d.createElement(s);js.id=id;js.src=\"http:\/\/connect.facebook.net\/es_ES\/sdk.js#xfbml=1&version=v2.8&appId=1672564249626860&status=true&cookie=true\";fjs.parentNode.insertBefore(js,fjs);}(document,'script','facebook-jssdk'));<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.expansion.com\/economia\/2019\/09\/02\/5d6cebce468aeb22378b458c.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] La ministra de Economa y Empresa en funciones, Nadia Calvio, ha asegurado que la economa espaola y su previsin para el prximo ao sera \u00abms positiva\u00bb si el pas contara ya con un Gobierno \u00abcon una perspectiva de estabilidad para los prximos cuatro aos\u00bb, que le permitira abordar los riesgos e incertidumbres a los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable - Favorite News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable - Favorite News\" \/>\n<meta property=\"og:description\" content=\"[ad_1] La ministra de Economa y Empresa en funciones, Nadia Calvio, ha asegurado que la economa espaola y su previsin para el prximo ao sera \u00abms positiva\u00bb si el pas contara ya con un Gobierno \u00abcon una perspectiva de estabilidad para los prximos cuatro aos\u00bb, que le permitira abordar los riesgos e incertidumbres a los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/\" \/>\n<meta property=\"og:site_name\" content=\"Favorite News\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-02T18:57:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-02T18:57:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/favorite-news.com\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"favorite-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"favorite-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/\"},\"author\":{\"name\":\"favorite-news\",\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/#\\\/schema\\\/person\\\/b91573b717dcfa5e4696032a9d28d3e8\"},\"headline\":\"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable\",\"datePublished\":\"2019-09-02T18:57:21+00:00\",\"dateModified\":\"2019-09-02T18:57:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/\"},\"wordCount\":472,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg\",\"articleSection\":[\"NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/\",\"url\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/\",\"name\":\"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable - Favorite News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg\",\"datePublished\":\"2019-09-02T18:57:21+00:00\",\"dateModified\":\"2019-09-02T18:57:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/#\\\/schema\\\/person\\\/b91573b717dcfa5e4696032a9d28d3e8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg\",\"contentUrl\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg\",\"width\":600,\"height\":315,\"caption\":\"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/\",\"name\":\"Favorite News\",\"description\":\"Favorite News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/#\\\/schema\\\/person\\\/b91573b717dcfa5e4696032a9d28d3e8\",\"name\":\"favorite-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c5a5cb12b74e9d517ee91cf570335b7d16177f1977cc91db161adfa435945a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c5a5cb12b74e9d517ee91cf570335b7d16177f1977cc91db161adfa435945a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c5a5cb12b74e9d517ee91cf570335b7d16177f1977cc91db161adfa435945a7?s=96&d=mm&r=g\",\"caption\":\"favorite-news\"},\"url\":\"https:\\\/\\\/favorite-news.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable - Favorite News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/","og_locale":"es_ES","og_type":"article","og_title":"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable - Favorite News","og_description":"[ad_1] La ministra de Economa y Empresa en funciones, Nadia Calvio, ha asegurado que la economa espaola y su previsin para el prximo ao sera \u00abms positiva\u00bb si el pas contara ya con un Gobierno \u00abcon una perspectiva de estabilidad para los prximos cuatro aos\u00bb, que le permitira abordar los riesgos e incertidumbres a los [&hellip;]","og_url":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/","og_site_name":"Favorite News","article_published_time":"2019-09-02T18:57:21+00:00","article_modified_time":"2019-09-02T18:57:22+00:00","og_image":[{"width":600,"height":315,"url":"https:\/\/favorite-news.com\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg","type":"image\/jpeg"}],"author":"favorite-news","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"favorite-news","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/#article","isPartOf":{"@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/"},"author":{"name":"favorite-news","@id":"https:\/\/favorite-news.com\/es\/#\/schema\/person\/b91573b717dcfa5e4696032a9d28d3e8"},"headline":"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable","datePublished":"2019-09-02T18:57:21+00:00","dateModified":"2019-09-02T18:57:22+00:00","mainEntityOfPage":{"@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/"},"wordCount":472,"commentCount":0,"image":{"@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/#primaryimage"},"thumbnailUrl":"https:\/\/favorite-news.com\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg","articleSection":["NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/","url":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/","name":"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable - Favorite News","isPartOf":{"@id":"https:\/\/favorite-news.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/#primaryimage"},"image":{"@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/#primaryimage"},"thumbnailUrl":"https:\/\/favorite-news.com\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg","datePublished":"2019-09-02T18:57:21+00:00","dateModified":"2019-09-02T18:57:22+00:00","author":{"@id":"https:\/\/favorite-news.com\/es\/#\/schema\/person\/b91573b717dcfa5e4696032a9d28d3e8"},"breadcrumb":{"@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/#primaryimage","url":"https:\/\/favorite-news.com\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg","contentUrl":"https:\/\/favorite-news.com\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/Calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera.jpg","width":600,"height":315,"caption":"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable"},{"@type":"BreadcrumbList","@id":"https:\/\/favorite-news.com\/es\/calvio-la-perspectiva-de-la-economa-espaola-para-2020-sera-ms-positiva-con-un-gobierno-estable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/favorite-news.com\/es\/"},{"@type":"ListItem","position":2,"name":"Calvio: la perspectiva de la economa espaola para 2020 sera ms positiva con un Gobierno estable"}]},{"@type":"WebSite","@id":"https:\/\/favorite-news.com\/es\/#website","url":"https:\/\/favorite-news.com\/es\/","name":"Favorite News","description":"Favorite News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/favorite-news.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/favorite-news.com\/es\/#\/schema\/person\/b91573b717dcfa5e4696032a9d28d3e8","name":"favorite-news","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c5a5cb12b74e9d517ee91cf570335b7d16177f1977cc91db161adfa435945a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c5a5cb12b74e9d517ee91cf570335b7d16177f1977cc91db161adfa435945a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c5a5cb12b74e9d517ee91cf570335b7d16177f1977cc91db161adfa435945a7?s=96&d=mm&r=g","caption":"favorite-news"},"url":"https:\/\/favorite-news.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/posts\/4039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/comments?post=4039"}],"version-history":[{"count":1,"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/posts\/4039\/revisions"}],"predecessor-version":[{"id":4041,"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/posts\/4039\/revisions\/4041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/media\/4040"}],"wp:attachment":[{"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/media?parent=4039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/categories?post=4039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/favorite-news.com\/es\/wp-json\/wp\/v2\/tags?post=4039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}